	{"id":547,"date":"2026-06-19T00:49:58","date_gmt":"2026-06-18T22:49:58","guid":{"rendered":"https:\/\/www.hotelnoemi.com\/?page_id=547"},"modified":"2026-07-15T11:41:38","modified_gmt":"2026-07-15T09:41:38","slug":"emplacement","status":"publish","type":"page","link":"https:\/\/www.hotelnoemi.com\/fr\/emplacement\/","title":{"rendered":"Emplacement"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\">Situ\u00e9 \u00e0 quelques pas de la place Saint-Marc, l&rsquo;Hotel Noemi est facilement accessible depuis l&rsquo;a\u00e9roport Marco Polo, la gare et la gare routi\u00e8re de Piazzale Roma ou du Tronchetto.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div style=\"--kalm-map-height: 600px\" class=\"kalm-map-block kalm-map-block--viewport wp-block-kalm-inn-google-map\">\n\t\t<iframe class=\"kalm-map-block__iframe\" title=\"Google Maps\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3959.4576488855673!2d12.336497917758782!3d45.43435215664795!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x477eb1d75eb79987%3A0x1fb277f738e89d5d!2sHotel%20Noemi!5e0!3m2!1sit!2sit!4v1781822877628!5m2!1sit!2sit\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\" allowfullscreen><\/iframe>\n\t<\/div>\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Comment nous rejoindre<\/h2>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"kalm-travel-card kalm-travel-card--car wp-block-kalm-inn-travel-card\">\n\t\t<i class=\"fa fa-car kalm-travel-card__icon\" aria-hidden=\"true\"><\/i>\n\t\t<h3 class=\"kalm-travel-card__title\">Voiture<\/h3>\n\t\t\t\t\t<p class=\"kalm-travel-card__text\">Dall\u2019autostrada A4, uscire al casello di Venezia Mestre e seguire le indicazioni per Venezia. Oltrepassato il Ponte della Libert\u00e0, parcheggiare l\u2019auto al Garage Comunale oppure al Garage San marco (la struttura \u00e8 convenzionata con Hotel Nemi, richiedere il coupon per ottenere uno speciale sconto). In Piazzale Roma prendete il vaporetto ACTV linea 1 (Direzione San Marco) e scendete alla fermata di Rialto. Una volta scesi, prendete Calle Bembo proprio di fronte alla fermata e proseguite dritti per circa 5 minuti, Hotel Noemi si trova in Calle dei Fabbri 909.<\/p>\n\t\t\t<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"kalm-travel-card kalm-travel-card--train wp-block-kalm-inn-travel-card\">\n\t\t<i class=\"fa fa-train kalm-travel-card__icon\" aria-hidden=\"true\"><\/i>\n\t\t<h3 class=\"kalm-travel-card__title\">Train<\/h3>\n\t\t\t\t\t<p class=\"kalm-travel-card__text\">Giunti in Stazione Santa Lucia, scendete i gradini e prendete il vaporetto ACTV linea 1 (Direzione San Marco) e scendete alla fermata di Rialto. Una volta scesi, prendete Calle Bembo proprio di fronte alla fermata e proseguite dritti per circa 5 minuti, Hotel Noemi si trova in Calle dei Fabbri 909.<\/p>\n\t\t\t<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"kalm-travel-card kalm-travel-card--plane wp-block-kalm-inn-travel-card\">\n\t\t<i class=\"fa fa-plane kalm-travel-card__icon\" aria-hidden=\"true\"><\/i>\n\t\t<h3 class=\"kalm-travel-card__title\">Avion<\/h3>\n\t\t\t\t\t<p class=\"kalm-travel-card__text\">Dall\u2019aeroporto \u201cMarco Polo\u201d di Venezia o \u201cCanova\u201d di Treviso, prendete il bus navetta della linea ACTV o della linea ATVO per Piazzale Roma. Da qui prendete il vaporetto ACTV linea 1 (Direzione San Marco) e scendete alla fermata di Rialto. Una volta scesi, prendete Calle Bembo proprio di fronte alla fermata e proseguite dritti per circa 5 minuti, Hotel Noemi si trova in Calle dei Fabbri 909.<\/p>\n\t\t\t<\/div><\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Situ\u00e9 \u00e0 quelques pas de la place Saint-Marc, l&rsquo;Hotel Noemi est facilement accessible depuis l&rsquo;a\u00e9roport Marco Polo, la gare et la gare routi\u00e8re de Piazzale Roma ou du Tronchetto. Comment nous rejoindre<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-547","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.hotelnoemi.com\/fr\/wp-json\/wp\/v2\/pages\/547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotelnoemi.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotelnoemi.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelnoemi.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelnoemi.com\/fr\/wp-json\/wp\/v2\/comments?post=547"}],"version-history":[{"count":1,"href":"https:\/\/www.hotelnoemi.com\/fr\/wp-json\/wp\/v2\/pages\/547\/revisions"}],"predecessor-version":[{"id":550,"href":"https:\/\/www.hotelnoemi.com\/fr\/wp-json\/wp\/v2\/pages\/547\/revisions\/550"}],"wp:attachment":[{"href":"https:\/\/www.hotelnoemi.com\/fr\/wp-json\/wp\/v2\/media?parent=547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}